{"id":149,"date":"2024-10-27T18:19:11","date_gmt":"2024-10-27T15:19:11","guid":{"rendered":"https:\/\/kakadoo-stu.de\/?page_id=149"},"modified":"2026-04-17T12:20:23","modified_gmt":"2026-04-17T09:20:23","slug":"datenschutzerklarung","status":"publish","type":"page","link":"https:\/\/kakadoo-stu.de\/de\/datenschutzerklarung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1. datenschutz auf einen Blick<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Allgemeine Hinweise<\/h3>\n\n\n\n<p>Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Datenerfassung auf dieser Website<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<\/h4>\n\n\n\n<p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Abschnitt \u201eHinweis zur Verantwortlichen Stelle\u201c in dieser Datenschutzerkl\u00e4rung entnehmen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wie erfassen wir Ihre Daten?<\/h4>\n\n\n\n<p>Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z. B. um Daten handeln, die Sie in ein Kontaktformular eingeben. Andere Daten werden automatisch oder nach Ihrer Einwilligung beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z. B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie diese Website betreten.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wof\u00fcr nutzen wir Ihre Daten?<\/h4>\n\n\n\n<p>Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden. Sofern \u00fcber die Website Vertr\u00e4ge geschlossen oder angebahnt werden k\u00f6nnen, werden die \u00fcbermittelten Daten auch f\u00fcr Vertragsangebote, Bestellungen oder sonstige Auftragsanfragen verarbeitet.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/h4>\n\n\n\n<p>Sie haben jederzeit das Recht, unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung oder L\u00f6schung dieser Daten zu verlangen. Wenn Sie eine Einwilligung zur Datenverarbeitung erteilt haben, k\u00f6nnen Sie diese Einwilligung jederzeit f\u00fcr die Zukunft widerrufen. Au\u00dferdem haben Sie das Recht, unter bestimmten Umst\u00e4nden die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu. Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Analyse-Tools und Tools von Drittanbietern<\/h3>\n\n\n\n<p>Beim Besuch dieser Website kann Ihr Surf-Verhalten statistisch ausgewertet werden. Das geschieht vor allem mit sogenannten Analyseprogrammen. Detaillierte Informationen zu diesen Analyseprogrammen finden Sie in der folgenden Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. das Hosting<\/h2>\n\n\n\n<p>Wir hosten die Inhalte unsererer Website bei folgendem Anbieter:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">HOSTINGER<\/h3>\n\n\n\n<p>Anbieter ist die HOSTINGER operations, UAB<\/p>\n\n\n\n<p>\u0160vitrigailos str. 34, Vilnius 03230 Litauen<\/p>\n\n\n\n<p>Telefon:&nbsp;<a href=\"tel:+37064503378\">+37064503378<\/a><\/p>\n\n\n\n<p>E-Mail:\u00a0<a href=\"mailto:domains@hostinger.com\">domains@hostinger.com<\/a>. Details entnehmen Sie der Datenschutzerkl\u00e4rung von <a href=\"https:\/\/www.hostinger.com\/de\/legal\/impressum\">hostinger<\/a>:\u00a0<a href=\"https:\/\/www.hostinger.com\/de\/legal\/impressum\">https:\/\/www.hostinger.com\/de\/legal\/impressum<\/a> Die Verwendung von Hetzner erfolgt auf Grundlage von Art. 6 Abs.. 1 lit. f DSGVO. Wir haben ein berechtigtes Interesse an einer m\u00f6glichst zuverl\u00e4ssigen Darstellung unsererer Website. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z. B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Auftragsverarbeitung<\/h4>\n\n\n\n<p>Wir haben einen Vertrag \u00fcber Auftragsverarbeitung (AVV) zur Nutzung des oben genannten Dienstes geschlossen. Hierbei handelt es sich um einen datenschutzrechtlich vorgeschriebenen Vertrag, der gew\u00e4hrleistet, dass dieser die personenbezogenen Daten unsererer Websitebesucher nur nach unseren Weisungen und unter Einhaltung der DSGVO verarbeitet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Allgemeine Hinweise und Pflichtinformationen<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Datenschutz<\/h3>\n\n\n\n<p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend den gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung. Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht. Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z. B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hinweise zur verantwortlichen Stelle<\/h3>\n\n\n\n<p>Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist: Serhieieva Alina KAKADOO hauptstrasse 24? 14806 dahnsdorf Telefon: +49 17664212236 E-Mail: support@kakadoo-stu.de Verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z. B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Speicherdauer<\/h3>\n\n\n\n<p>Soweit innerhalb dieser Datenschutzerkl\u00e4rung keine speziellere Speicherdauer genannt wurde, verbleiben Ihre personenbezogenen Daten bei uns, bis der Zweck f\u00fcr die Datenverarbeitung entf\u00e4llt. Wenn Sie ein berechtigtes L\u00f6schersuchen geltend machen oder eine Einwilligung zur Datenverarbeitung widerrufen, werden Ihre Daten gel\u00f6scht, sofern wir keine anderen rechtlich zul\u00e4ssigen Gr\u00fcnde f\u00fcr die Speicherung Ihrer personenbezogenen Daten haben (z. B. steuer- oder handelsrechtliche Aufbewahrungsfristen); im letztgenannten Fall erfolgt die L\u00f6schung nach Fortfall dieser Gr\u00fcnde.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Allgemeine Hinweise zu den Rechtsgrundlagen der Datenverarbeitung auf dieser Website<\/h3>\n\n\n\n<p>Sofern Sie in die Datenverarbeitung eingewilligt haben, verarbeiten wir Ihre personenbezogenen Daten auf Grundlage von Art. 6 Abs.. 1 lit. a DSGVO bzw. Art. 9 Abs. 2 lit. a DSGVO, sofern besondere Datenkategorien nach Art. 9 Abs. 1 DSGVO verarbeitet werden. Im Falle einer ausdr\u00fccklichen Einwilligung in die \u00dcbertragung personenbezogener Daten in Drittstaaten erfolgt die Datenverarbeitung au\u00dferdem auf Grundlage von Art. 49 Abs. 1 lit. a DSGVO. Sofern Sie in die Speicherung von Cookies oder in den Zugriff auf Informationen in Ihrem Endger\u00e4t (z. B. via Device-Fingerprinting) eingewilligt haben, erfolgt die Datenverarbeitung zus\u00e4tzlich auf Grundlage von \u00a7 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar. Sind Ihre Daten zur Vertragserf\u00fcllung oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich, verarbeiten wir Ihre Daten auf Grundlage des Art. 6 Abs. 1 lit. b DSGVO. Des Weiteren verarbeiten wir Ihre Daten, sofern diese zur Erf\u00fcllung einer rechtlichen Verpflichtung erforderlich sind auf Grundlage von Art. 6 Abs. 1 lit. c DSGVO. Die Datenverarbeitung kann ferner auf Grundlage unseres berechtigten Interesses nach Art. 6 Abs. 1 lit. f DSGVO erfolgen. \u00dcber die jeweils im Einzelfall einschl\u00e4gigen Rechtsgrundlagen wird in den folgenden Abs\u00e4tzen dieser Datenschutzerkl\u00e4rung informiert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hinweis zur Datenweitergabe in datenschutzrechtlich nicht sicheren Drittstaaten sowie die Weitergabe an US-Unternehmen, die nicht DPF-zertifiziert sind<\/h3>\n\n\n\n<p>Wir verwenden unter anderem Tools von Unternehmen mit Sitz in datenschutzrechtlich nicht sicheren Drittstaaten sowie US-Tools, deren Anbieter nicht nach dem EU-US-Data Privacy Framework (DPF) zertifiziert sind. Wenn diese Tools aktiv sind, k\u00f6nnen Ihre personenbezogenene Daten in diese Staaten \u00fcbertragen und dort verarbeitet werden. Wir weisen darauf hin, dass in datenschutzrechtlich unsicheren Drittstaaten kein mit der EU vergleichbares Datenschutzniveau garantiert werden kann. Wir weisen darauf hin, dass die USA als sicherer Drittstaat grunds\u00e4tzlich ein mit der EU vergleichbares Datenschutzniveau aufweisen. Eine Daten\u00fcbertragung in die USA ist danach zul\u00e4ssig, wenn der Empf\u00e4nger eine Zertifizierung unter dem \u201eEU-US Data Privacy Framework\u201c (DPF) besitzt oder \u00fcber geeignete zus\u00e4tzliche Garantien verf\u00fcgt. Informationen zu \u00dcbermittlungen an Drittstaaten einschlie\u00dflich der Datenempf\u00e4nger finden Sie in dieser Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Empf\u00e4nger von personenbezogenen Daten<\/h3>\n\n\n\n<p>Im Rahmen unsererer Gesch\u00e4ftst\u00e4tigkeit arbeiten wir mit verschiedenenen externen Stellen zusammen. Dabei ist teilweise auch eine \u00dcbermittlung von personenbezogenen Daten an diese externen Stellen erforderlich. Wir geben personenbezogene Daten nur dann an externe Stellen weiter, wenn dies im Rahmen einer Vertragserf\u00fcllung erforderlich ist, wenn wir gesetzlich hierzu verpflichtet sind (z. B. Weitergabe von Daten an Steuerbeh\u00f6rden), wenn wir ein berechtigtes Interesse nach Art. 6 Abs. 1 lit. f DSGVO an der Weitergabe haben oder wenn eine sonstige Rechtsgrundlage die Datenweitergabe erlaubt. Beim Einsatz von Auftragsverarbeitern geben wir personenbezogene Daten unsererer Kunden nur auf Grundlage eines g\u00fcltigen Vertrags \u00fcber Auftragsverarbeitung weiter. Im Falle einer gemeinsamen Verarbeitung wird ein Vertrag \u00fcber gemeinsame Verarbeitung geschlossen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/h3>\n\n\n\n<p>Viele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Widerspruchsrecht gegen die Datenerhebung in besonderen F\u00e4llen sowie gegen Direktwerbung (Art. 21 DSGVO)<\/h3>\n\n\n\n<p>WENN DIE DATENVERARBEITUNG AUF GRUNDLAGE VON ART. 6 ABS. 1 LIT. E ODER F DSGVO ERFOLGT, HABEN SIE JEDERZEIT DAS RECHT, AUS GR\u00dcNDEN, DIE SICH AUS IHRER BESONDEREN SITUATION ERGEBEN, GEGEN DIE VERARBEITUNG IHRER PERSONENBEZOGENEN DATEN WIDERSPRUCH EINZULEGEN; DIES GILT AUCH F\u00dcR EIN AUF DIESE BESTIMMUNGEN GEST\u00dcTZTES PROFILING. DIE JEWEILIGE RECHTSGRUNDLAGE, AUF DENEN EINE VERARBEITUNG BERUHT, ENTNEHMEN SIE DIESER DATENSCHUTZERKL\u00c4RUNG. WENN SIE WIDERSPRUCH EINLEGEN, WERDEN WIR IHRE BETROFFENEN PERSONENBEZOGENEN DATEN NICHT MEHR VERARBEITEN, ES SEI DENN, WIR K\u00d6NNEN ZWINGENDE SCHUTZW\u00dcRDIGE GR\u00dcNDE F\u00dcR DIE VERARBEITUNG NACHWEISEN, DIE IHRE INTERESSEN, RECHTE UND FREIHEITEN \u00dcBERWIEGEN ODER DIE VERARBEITUNG DIENT DER GELTENDMACHUNG, AUS\u00dcBUNG ODER VERTEIDIGUNG VON RECHTSANSPR\u00dcCHEN (WIDERSPRUCH NACH ART. 21 ABS. 1 DSGVO). WERDEN IHRE PERSONENBEZOGENEN DATEN VERARBEITET, UM DIREKTWERBUNG ZU BETREIBEN, SO HABEN SIE DAS RECHT, JEDERZEIT WIDERSPRUCH GEGEN DIE VERARBEITUNG SIE BETREFFENDER PERSONENBEZOGENER DATEN ZUM ZWECKE DERARTIGER WERBUNG EINZULEGEN; DIES GILT AUCH F\u00dcR DAS PROFILING, SOWEIT ES MIT SOLCHER DIREKTWERBUNG IN VERBINDUNG STEHT. WENN SIE WIDERSPRECHEN, WERDEN IHRE PERSONENBEZOGENEN DATEN ANSCHLIESSEND NICHT MEHR ZUM ZWECKE DER DIREKTWERBUNG VERWENDET (WIDERSPRUCH NACH ART. 21 ABS. 2 DSGVO).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde<\/h3>\n\n\n\n<p>Im Falle von Verst\u00f6\u00dfen gegen die DSGVO steht den Betroffenen ein Beschwerderecht bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres gew\u00f6hnlichen Aufenthalts, ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes zu. Das Beschwerderecht besteht unbeschadet anderweitiger verwaltungsrechtlicher oder gerichtlicher Rechtsbehelfe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recht auf Daten\u00fcbertragbarkeit<\/h3>\n\n\n\n<p>Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Auskunft, Berichtigung und L\u00f6schung<\/h3>\n\n\n\n<p>Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung oder L\u00f6schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recht auf Einschr\u00e4nkung der Verarbeitung<\/h3>\n\n\n\n<p>Sie haben das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Hierzu k\u00f6nnen Sie sich jederzeit an uns wenden. Das Recht auf Einschr\u00e4nkung der Verarbeitung besteht in folgenden F\u00e4llen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wenn Sie die Richtigkeit Ihrer bei uns gespeicherten personenbezogenen Daten bestreiten, ben\u00f6tigen wir in der Regel Zeit, um dies zu \u00fcberpr\u00fcfen. F\u00fcr die Dauer der Pr\u00fcfung haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n\n\n\n<li>Wenn die Verarbeitung Ihrer personenbezogenen Daten unrechtm\u00e4\u00dfig geschah\/geschieht, k\u00f6nnen Sie statt der L\u00f6schung die Einschr\u00e4nkung der Datenverarbeitung verlangen.<\/li>\n\n\n\n<li>Wenn wir Ihre personenbezogenen Daten nicht mehr ben\u00f6tigen, Sie sie jedoch zur Aus\u00fcbung, Verteidigung oder Geltendmachung von Rechtsanspr\u00fcchen ben\u00f6tigen, haben Sie das Recht, statt der L\u00f6schung die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n\n\n\n<li>Wenn Sie einen Widerspruch nach Art. 21 Abs.. 1 DSGVO eingelegt haben, muss eine Abw\u00e4gung zwischen Ihren und unseren Interessen vorgenommen werden. Solange noch nicht feststeht, wessen Interessen \u00fcberwiegen, haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<\/ul>\n\n\n\n<p>Wenn Sie die Verarbeitung Ihrer personenbezogenen Daten eingeschr\u00e4nkt haben, d\u00fcrfen diese Daten - von ihrer Speicherung abgesehen - nur mit Ihrer Einwilligung oder zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person oder aus Gr\u00fcnden eines wichtigen \u00f6ffentlichen Interesses der Europ\u00e4ischen Union oder eines Mitgliedstaats verarbeitet werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SSL- bzw. TLS-Verschl\u00fcsselung<\/h3>\n\n\n\n<p>Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL- bzw. TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201ehttp:\/\/\u201c auf \u201ehttps:\/\/\u201c wechselt und an dem Schloss-Symbol in Ihrer Browserzeile. Wenn die SSL- bzw. TLS-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4. die Datenerfassung auf dieser Website<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Cookies<\/h3>\n\n\n\n<p>Unsere Internetseiten verwenden so genannte \u201eCookies\u201c. Cookies sind kleine Datenpakete und richten auf Ihrem Endger\u00e4t keinen Schaden an. Sie werden entweder vor\u00fcbergehend f\u00fcr die Dauer einer Sitzung (Session-Cookies) oder dauerhaft (permanente Cookies) auf Ihrem Endger\u00e4t gespeichert. Session-Cookies werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Permanente Cookies bleiben auf Ihrem Endger\u00e4t gespeichert, bis Sie diese selbst l\u00f6schen oder eine automatische L\u00f6schung durch Ihren Webbrowser erfolgt. Cookies k\u00f6nnen von uns (First-Party-Cookies) oder von Drittunternehmen stammen (sog. Third-Party-Cookies). Third-Party-Cookies erm\u00f6glichen die Einbindung bestimmung bestimmter Dienstleistungen von Drittunternehmen innerhalb von Webseiten (z. B. Cookies zur Abwicklung von Zahlungsdienstleistungen). Cookies haben verschiedene Funktionen. Zahlreiche Cookies sind technisch notwendig, da bestimmte Webseitenfunktionen ohne diese nicht funktionieren w\u00fcrden (z. B. die Warenkorbfunktion oder die Anzeige von Videos). Andere Cookies k\u00f6nnen zur Auswertung des Nutzerverhaltens oder zu Werbezwecken verwendet werden. Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs, zur Bereitstellung bestimmimmter, von Ihnen erw\u00fcnschter Funktionen (z. B. f\u00fcr die Warenkorbfunktion) oder zur Optimierung der Website (z. B. Cookies zur Messung des Webpublikums) erforderlich sind (notwendige Cookies), werden auf Grundlage von Art. 6 Abs.. 1 lit. f DSGVO gespeichert, sofern keine andere Rechtsgrundlage angef\u00fchrt wird. Der Websitebetreiber hat ein berechtigtes Interesse an der Speicherung von notwendigen Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Sofern eine Einwilligung zur Speicherung von Cookies und vergleichbaren Wiedererkennungstechnologien abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage dieser Einwilligung (Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG); die Einwilligung ist jederzeit widerrufbar. Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browsers aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein. Welche Cookies und Dienste auf dieser Website eingesetzt werden, k\u00f6nnen Sie dieser Datenschutzerkl\u00e4rung entnehmen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Zustimmung mit CookieYes<\/strong><\/h3>\n\n\n\n<p>Unsere Website nutzt die Consent-Technologie von <strong>CookieYes<\/strong>, um Ihre Einwilligung zur Speicherung bestimmter Cookies in Ihrem Browser oder zum Einsatz bestimmter Technologien einzuholen und diese datenschutzkonform zu dokumentieren. Anbieter dieser Technologie ist <strong>CookieYes Limited<\/strong>, 3 Warren Yard, Wolverton Mill, Milton Keynes, MK12 5NW, Vereinigtes K\u00f6nigreich (im Folgenden \u201eCookieYes\u201c).<\/p>\n\n\n\n<p>Wenn Sie unsere Website betreten, wird ein CookieYes-Cookie in Ihrem Browser gespeichert, in dem die von Ihnen erteilten Einwilligungen oder der Widerruf dieser Einwilligungen gespeichert werden. Diese Daten werden nicht an CookieYes weitergegeben.<\/p>\n\n\n\n<p>Die erfassten Daten werden gespeichert, bis Sie uns zur L\u00f6schung auffordern bzw. das CookieYes-Cookie selbst l\u00f6schen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt. Zwingende gesetzliche Aufbewahrungsfristen bleiben unber\u00fchrt.<\/p>\n\n\n\n<p>Details zur Datenverarbeitung von CookieYes finden Sie unter:<br><a href=\"https:\/\/www.cookieyes.com\/privacy-policy\/\">https:\/\/www.cookieyes.com\/privacy-policy\/<\/a><\/p>\n\n\n\n<p>Der Einsatz der CookieYes-Consent-Technology erfolgt, um die gesetzlich vorgeschriebenen Einwilligungen f\u00fcr den Einsatz von Cookies einzuholen. Rechtsgrundlage hierf\u00fcr ist <strong>Art. 6 Abs.. 1 lit. c DSGVO<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Server-Log-Dateien<\/h3>\n\n\n\n<p>Der Provider der Seiten erhebt und speichert automatisch Informationen in so genannten Server-Log-Dateien, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Browsertyp und Browserversion<\/li>\n\n\n\n<li>verwendetes Betriebssystem<\/li>\n\n\n\n<li>Referrer URL<\/li>\n\n\n\n<li>Hostname des zugreifenden Rechners<\/li>\n\n\n\n<li>Uhrzeit der Serveranfrage<\/li>\n\n\n\n<li>IP-Adresse<\/li>\n<\/ul>\n\n\n\n<p>Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen. Die Erfassung dieser Daten erfolgt auf Grundlage von Art. 6 Abs.. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an der technisch fehlerfreien Darstellung und der Optimierung seiner Website - hierzu m\u00fcssen die Server-Log-Files erfasst werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Kontaktformular<\/h3>\n\n\n\n<p>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter. Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO), sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar. Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z. B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen - insbesondere Aufbewahrungsfristen - bleiben unber\u00fchrt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Anfrage per E-Mail, Telefon oder Telefax<\/h3>\n\n\n\n<p>Wenn Sie uns per E-Mail, Telefon oder Telefax kontaktieren, wird Ihre Anfrage inklusive aller daraus hervorgehenden personenbezogenen Daten (Name, Anfrage) zum Zwecke der Bearbeitung Ihres Anliegens bei uns gespeichert und verarbeitet. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter. Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrages zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO), sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar. Die von Ihnen an uns per Kontaktanfragen \u00fcbersandten Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z. B. nach abgeschlossener Bearbeitung Ihres Anliegens). Zwingende gesetzliche Bestimmungen - insbesondere gesetzliche Aufbewahrungsfristen - bleiben unber\u00fchrt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Auftragsverarbeitung<\/h4>\n\n\n\n<p>Wir haben einen Vertrag \u00fcber Auftragsverarbeitung (AVV) zur Nutzung des oben genannten Dienstes geschlossen. Hierbei handelt es sich um einen datenschutzrechtlich vorgeschriebenen Vertrag, der gew\u00e4hrleistet, dass dieser die personenbezogenen Daten unsererer Websitebesucher nur nach unseren Weisungen und unter Einhaltung der DSGVO verarbeitet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5. Analyse-Tools und Werbung<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Google Tag Manager<\/h3>\n\n\n\n<p>Wir setzen den Google Tag Manager ein. Anbieter ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland. Der Google Tag Manager ist ein Tool, mit dessen Hilfe wir Tracking- oder Statistik-Tools und andere Technologien auf unserer Website einbinden k\u00f6nnen. Der Google Tag Manager selbst erstellt keine Nutzerprofile, speichert keine Cookies und nimmt keine eigenst\u00e4ndigen Analysen vor. Er dient lediglich der Verwaltung und Ausspielung der \u00fcber ihn eingebundenen Tools. Der Google Tag Manager erfasst jedoch Ihre IP-Adresse, die auch an das Mutterunternehmen von Google in die Vereinigten Staaten \u00fcbertragen werden kann. Der Einsatz des Google Tag Managers erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an einer schnellen und unkomplizierten Einbindung und Verwaltung verschiedener Tools auf seiner Website. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z. B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar. Das Unternehmen verf\u00fcgt \u00fcber eine Zertifizierung nach dem \u201eEU-US Data Privacy Framework\u201c (DPF). Der DPF ist ein \u00dcbereinkommen zwischen der Europ\u00e4ischen Union und den USA, der die die Einhaltung europ\u00e4ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew\u00e4hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link:&nbsp;<a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Google Analytics<\/h3>\n\n\n\n<p>Diese Website nutzt Funktionen des Webanalysedienstes Google Analytics. Anbieter ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland. Google Analytics erm\u00f6glicht es dem Websitebetreiber, das Verhalten der Websitebesucher zu analysieren. Hierbei erh\u00e4lt der Websitebetreiber verschiedene Nutzungsdaten, wie z. B. Seitenaufrufe, Verweildauer, verwendete Betriebssysteme und Herkunft des Nutzers. Diese Daten werden in einer User-ID zusammengefasst und dem jeweiligen Endger\u00e4t des Websitebesuchers zugeordnet. Des Weiteren k\u00f6nnen wir mit Google Analytics u. a. Ihre Maus- und Scrollbewegungen und Klicks aufzeichnen. Ferner verwendet Google Analytics verschiedene Modellierungsans\u00e4tze, um die erfassten Datens\u00e4tze zu erg\u00e4nzen und setzt Machine-Learning-Technologien bei der Datenanalyse ein. Google Analytics verwendet Technologien, die die Wiedererkennung des Nutzers zum Zwecke der Analyse des Nutzerverhaltens erm\u00f6glichen (z. B. Cookies oder Device-Fingerprinting). Die von Google erfassten Informationen \u00fcber die Benutzung dieser Website werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Die Nutzung dieses Dienstes erfolgt auf Grundlage Ihrer Einwilligung nach Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar. Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier:&nbsp;<a href=\"https:\/\/business.safety.google\/adscontrollerterms\/sccs\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/business.safety.google\/adscontrollerterms\/sccs\/<\/a>. Das Unternehmen verf\u00fcgt \u00fcber eine Zertifizierung nach dem \u201eEU-US Data Privacy Framework\u201c (DPF). Der DPF ist ein \u00dcbereinkommen zwischen der Europ\u00e4ischen Union und den USA, der die Einhaltung europ\u00e4ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew\u00e4hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link:&nbsp;<a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">IP-Anonymisierung<\/h4>\n\n\n\n<p>Die Google Analytics IP-Anonymisierung ist aktiviert. Dadurch wird Ihre IP-Adresse von Google innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum vor der \u00dcbermittlung in die USA gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Im Auftrag des Betreibers dieser Website wird Google diese Informationen benutzen, um Ihre Nutzung der Website auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen gegen\u00fcber dem Websitebetreiber zu erbringen. Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Browser-Plugin<\/h4>\n\n\n\n<p>Sie k\u00f6nnen die Erfassung und Verarbeitung Ihrer Daten durch Google verhindern, indem Sie das unter dem folgenden Link verf\u00fcgbare Browser-Plugin herunterladen und installieren:&nbsp;<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>. Mehr Informationen zum Umgang mit Nutzerdaten bei Google Analytics finden Sie in der Datenschutzerkl\u00e4rung von Google:&nbsp;<a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Auftragsverarbeitung<\/h4>\n\n\n\n<p>Wir haben mit Google einen Vertrag zur Auftragsverarbeitung abgeschlossen und setzen die strengen Vorgaben der deutschen Datenschutzbeh\u00f6rden bei der Nutzung von Google Analytics vollst\u00e4ndig um.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Google-Anzeigen<\/h3>\n\n\n\n<p>Der Websitebetreiber verwendet Google Ads. Google Ads ist ein Online-Werbeprogramm der Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland. Google Ads erm\u00f6glicht es uns Werbeanzeigen in der Google-Suchmaschine oder auf Drittwebseiten auszuspielen, wenn der Nutzer bestimmte Suchbegriffe bei Google eingibt (Keyword-Targeting). Ferner k\u00f6nnen zielgerichtete Werbeanzeigen anhand der bei Google vorhandenen Nutzerdaten (z. B. Standortdaten und Interessen) ausgespielt werden (Zielgruppen-Targeting). Wir als Websitebetreiber k\u00f6nnen diese Daten quantitativ auswerten, indem wir beispielsweise analysieren, welche Suchbegriffe zur Ausspielung unsererer Werbeanzeigen gef\u00fchrt haben und wie viele Anzeigen zu entsprechenden Klicks gef\u00fchrt haben. Die Nutzung dieses Dienstes erfolgt auf Grundlage Ihrer Einwilligung nach Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar. Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier:&nbsp;<a href=\"https:\/\/policies.google.com\/privacy\/frameworks\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/privacy\/frameworks<\/a>&nbsp;und&nbsp;<a href=\"https:\/\/business.safety.google\/controllerterms\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/business.safety.google\/controllerterms\/<\/a>. Das Unternehmen verf\u00fcgt \u00fcber eine Zertifizierung nach dem \u201eEU-US Data Privacy Framework\u201c (DPF). Der DPF ist ein \u00dcbereinkommen zwischen der Europ\u00e4ischen Union und den USA, der die Einhaltung europ\u00e4ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew\u00e4hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link:&nbsp;<a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Google Ads Remarketing<\/h3>\n\n\n\n<p>Diese Website nutzt die Funktionen von Google Ads Remarketing. Anbieter ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland. Mit Google Ads Remarketing k\u00f6nnen wir Personen, die mit unserem Online-Angebot interagieren bestimmten Zielgruppen zuordnen, um ihnen anschlie\u00dfend interessenbezogene Werbung im Google-Werbenetzwerk anzeigen zu lassen (Remarketing bzw. Retargeting). Des Weiteren k\u00f6nnen die mit Google Ads Remarketing erstellten Werbe-Zielgruppen mit den ger\u00e4te\u00fcbergreifenden Funktionen von Google verkn\u00fcpft werden. Auf diese Weise k\u00f6nnen interessenbezogene, personalisierte Werbebotschaften, die in Abh\u00e4ngigkeit Ihres fr\u00fcheren Nutzungs- und Surfverhaltens auf einem Endger\u00e4t (z. B. Handy) an Sie angepasst wurden auch auf einem anderen Ihrer Endger\u00e4te (z. B. Tablet oder PC) angezeigt werden. Wenn Sie \u00fcber einen Google-Account verf\u00fcgen, k\u00f6nnen Sie der personalisierten Werbung unter folgendem Link widersprechen:&nbsp;<a href=\"https:\/\/adssettings.google.com\/anonymous?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/adssettings.google.com\/anonymous?hl=de<\/a>. Die Nutzung dieses Dienstes erfolgt auf Grundlage Ihrer Einwilligung nach Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar. Weitergehende Informationen und die Datenschutzbestimmungen finden Sie in der Datenschutzerkl\u00e4rung von Google unter:&nbsp;<a href=\"https:\/\/policies.google.com\/technologies\/ads?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/technologies\/ads?hl=de<\/a>. Das Unternehmen verf\u00fcgt \u00fcber eine Zertifizierung nach dem \u201eEU-US Data Privacy Framework\u201c (DPF). Der DPF ist ein \u00dcbereinkommen zwischen der Europ\u00e4ischen Union und den USA, der die Einhaltung europ\u00e4ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew\u00e4hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link:&nbsp;<a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Zielgruppenbildung mit Kundenabgleich<\/h4>\n\n\n\n<p>Zur Zielgruppenbildung verwenden wir unter anderem den Kundenabgleich von Google Ads Remarketing. Hierbei \u00fcbergeben wir bestimmte Kundendaten (z. B. E-Mail-Adressen) aus unserenen Kundenlisten an Google. Sind die betreffenden Kunden Google-Nutzer und in ihrem Google-Konto eingeloggt, werden ihnen passende Werbebotschaften innerhalb des Google-Netzwerks (z. B. bei YouTube, Gmail oder in der Suchmaschine) angezeigt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Google Conversion-Tracking<\/h3>\n\n\n\n<p>Diese Website nutzt Google Conversion Tracking. Anbieter ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland. Mit Hilfe von Google-Conversion-Tracking k\u00f6nnen Google und wir erkennen, ob der Nutzer bestimmte Aktionen durchgef\u00fchrt hat. So k\u00f6nnen wir beispielsweise auswerten, welche Buttons auf unserer Website wie h\u00e4ufig geklickt und welche Produkte besonders h\u00e4ufig angesehen oder gekauft wurden. Diese Informationen dienen dazu, Conversion-Statistiken zu erstellen. Wir erfahren die Gesamtanzahl der Nutzer, die auf unsere Anzeigen geklickt haben und welche Aktionen sie durchgef\u00fchrt haben. Wir erhalten keine Informationen, mit denen wir den Nutzer pers\u00f6nlich identifizieren k\u00f6nnen. Google selbst nutzt zur Identifikation Cookies oder vergleichbare Wiedererkennungstechnologien. Die Nutzung dieses Dienstes erfolgt auf Grundlage Ihrer Einwilligung nach Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar. Mehr Informationen zu Google Conversion-Tracking finden Sie in den Datenschutzbestimmungen von Google:&nbsp;<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/privacy?hl=de<\/a>. Das Unternehmen verf\u00fcgt \u00fcber eine Zertifizierung nach dem \u201eEU-US Data Privacy Framework\u201c (DPF). Der DPF ist ein \u00dcbereinkommen zwischen der Europ\u00e4ischen Union und den USA, der die Einhaltung europ\u00e4ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew\u00e4hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link:&nbsp;<a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">6. Plugins und Tools<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Google-Schriftarten (lokales Hosting)<\/h3>\n\n\n\n<p>Diese Seite nutzt zur einheitlichen Darstellung von Schriftarten so genannte Google Fonts, die von Google bereitgestellt werden. Die Google Fonts sind lokal installiert. Eine Verbindung zu Servern von Google findet dabei nicht statt. Weitere Informationen zu Google Fonts finden Sie unter&nbsp;<a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/developers.google.com\/fonts\/faq<\/a>&nbsp;und in der Datenschutzerkl\u00e4rung von Google:&nbsp;<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SolidWP<\/h3>\n\n\n\n<p>Wir haben SolidWP auf dieser Website eingebunden. Anbieter ist die iThemes Media LLC, 1720 South Kelly Avenue Edmond, OK 73013, USA (nachfolgend \u201eSolidWP\u201c). SolidWP dient dem Schutz unsererer Website vor unerw\u00fcnschten Zugriffen oder b\u00f6sartigen Cyberattacken. Zu diesem Zweck erfasst SolidWP u. a. Ihre IP-Adresse, Zeitpunkt und Quelle von Login-Versuchen und Log-Daten (z. B. den verwendeten Browser). SolidWP wird lokal auf unseren Servern installiert. SolidWP \u00fcbermittelt IP-Adressen von wiederkehrenden Angreifern an eine zentrale Datenbank von SolidWP in die USA (Network Brute Force Protection), um derartige Angriffe k\u00fcnftig zu unterbinden. Die Verwendung von SolidWP erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an einem m\u00f6glichst effektiven Schutz seiner Website vor Cyberattacken. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z. B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Verwendung von Bitrix24 \/ Alaio Cloud (ehemals Bitrix24)<\/h3>\n\n\n\n<p>Wir verwenden den Dienst&nbsp;<strong>Bitrix24<\/strong>&nbsp;(betrieben von&nbsp;<strong>Alaio Cloud Limited<\/strong>, Registrierungsnummer HE387206, Sitz: Frema House, office 102, No. 9 Constantinou Paparigopoulou Str., 3106 Limassol, Zypern) f\u00fcr CRM-Funktionen, Kontaktformulare, Chat-Widgets etc.<br>F\u00fcr Nutzer bzw. Daten\u00fcbertragung in die USA gilt die Zugeh\u00f6rigkeit zu&nbsp;<strong>Alaio Inc.<\/strong>, 700 North Fairfax St., Suite 614-B, Alexandria, VA 22314, USA.<\/p>\n\n\n\n<p>Die Nutzung von Bitrix24 erfolgt zur effizienten Kundenkommunikation und Datenverwaltung auf Basis von&nbsp;<strong>Art. 6 Abs.. 1 lit. f DSGVO<\/strong>&nbsp;(berechtigtes Interesse).<br>S\u00e4mtliche Kundendaten, die \u00fcber Formulare oder Chat erhoben werden, werden in Bitrix24 gespeichert und verarbeitet.<\/p>\n\n\n\n<p>Da Daten m\u00f6glicherweise au\u00dferhalb der EU \u00fcbertragen werden, besteht ein&nbsp;<strong>Vertrag zur Auftragsverarbeitung (AVV)<\/strong>&nbsp;mit Alaio\/Bitrix, der die Anforderungen von&nbsp;<strong>Art. 28 DSGVO<\/strong>&nbsp;entspricht.<\/p>\n\n\n\n<p>Weitere Informationen zum Datenschutz bei Bitrix \/ Alaio finden Sie unter:<br><a>https:\/\/www.bitrix24.de\/privacy\/<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf dieser Website [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":215,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-full-width.php","meta":{"footnotes":""},"class_list":["post-149","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz\u00aderkl\u00e4rung - Web \u0441\u0442\u0443\u0434\u0438\u044f Kakadoo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kakadoo-stu.de\/de\/datenschutzerklarung\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Datenschutz\u00aderkl\u00e4rung - Web \u0441\u0442\u0443\u0434\u0438\u044f Kakadoo\" \/>\n<meta name=\"twitter:description\" content=\"1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf dieser Website [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kakadoo-stu.de\/wp-content\/uploads\/2024\/10\/transparent-logo.png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/datenschutzerklarung\\\/\",\"url\":\"https:\\\/\\\/kakadoo-stu.de\\\/datenschutzerklarung\\\/\",\"name\":\"Datenschutz\u00aderkl\u00e4rung - Web \u0441\u0442\u0443\u0434\u0438\u044f Kakadoo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/datenschutzerklarung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/datenschutzerklarung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kakadoo-stu.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/transparent-logo.png\",\"datePublished\":\"2024-10-27T15:19:11+00:00\",\"dateModified\":\"2026-04-17T09:20:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/datenschutzerklarung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kakadoo-stu.de\\\/datenschutzerklarung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/datenschutzerklarung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kakadoo-stu.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/transparent-logo.png\",\"contentUrl\":\"https:\\\/\\\/kakadoo-stu.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/transparent-logo.png\",\"width\":445,\"height\":115,\"caption\":\"\u041b\u043e\u0433\u043e\u0442\u0438\u043f \u0441\u0442\u0443\u0434\u0438\u0438 \u043f\u043e \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u044e \u0441\u0430\u0439\u0442\u043e\u0432, \u0434\u0438\u0437\u0430\u0439\u043d\u0443 \u0438 \u0421\u0415\u041e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/datenschutzerklarung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/kakadoo-stu.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\u00aderkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/#website\",\"url\":\"https:\\\/\\\/kakadoo-stu.de\\\/\",\"name\":\"kakadoo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kakadoo-stu.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/#organization\",\"name\":\"kakadoo\",\"url\":\"https:\\\/\\\/kakadoo-stu.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kakadoo-stu.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/kakadoo-logo.png\",\"contentUrl\":\"https:\\\/\\\/kakadoo-stu.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/kakadoo-logo.png\",\"width\":445,\"height\":115,\"caption\":\"kakadoo\"},\"image\":{\"@id\":\"https:\\\/\\\/kakadoo-stu.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kakadoostudio\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - Kakadoo Web Studio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kakadoo-stu.de\/de\/datenschutzerklarung\/","twitter_card":"summary_large_image","twitter_title":"Datenschutz\u00aderkl\u00e4rung - Web \u0441\u0442\u0443\u0434\u0438\u044f Kakadoo","twitter_description":"1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf dieser Website [&hellip;]","twitter_image":"https:\/\/kakadoo-stu.de\/wp-content\/uploads\/2024\/10\/transparent-logo.png","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kakadoo-stu.de\/datenschutzerklarung\/","url":"https:\/\/kakadoo-stu.de\/datenschutzerklarung\/","name":"Datenschutzerkl\u00e4rung - Kakadoo Web Studio","isPartOf":{"@id":"https:\/\/kakadoo-stu.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kakadoo-stu.de\/datenschutzerklarung\/#primaryimage"},"image":{"@id":"https:\/\/kakadoo-stu.de\/datenschutzerklarung\/#primaryimage"},"thumbnailUrl":"https:\/\/kakadoo-stu.de\/wp-content\/uploads\/2024\/10\/transparent-logo.png","datePublished":"2024-10-27T15:19:11+00:00","dateModified":"2026-04-17T09:20:23+00:00","breadcrumb":{"@id":"https:\/\/kakadoo-stu.de\/datenschutzerklarung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kakadoo-stu.de\/datenschutzerklarung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kakadoo-stu.de\/datenschutzerklarung\/#primaryimage","url":"https:\/\/kakadoo-stu.de\/wp-content\/uploads\/2024\/10\/transparent-logo.png","contentUrl":"https:\/\/kakadoo-stu.de\/wp-content\/uploads\/2024\/10\/transparent-logo.png","width":445,"height":115,"caption":"\u041b\u043e\u0433\u043e\u0442\u0438\u043f \u0441\u0442\u0443\u0434\u0438\u0438 \u043f\u043e \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u044e \u0441\u0430\u0439\u0442\u043e\u0432, \u0434\u0438\u0437\u0430\u0439\u043d\u0443 \u0438 \u0421\u0415\u041e"},{"@type":"BreadcrumbList","@id":"https:\/\/kakadoo-stu.de\/datenschutzerklarung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/kakadoo-stu.de\/"},{"@type":"ListItem","position":2,"name":"Datenschutz\u00aderkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/kakadoo-stu.de\/#website","url":"https:\/\/kakadoo-stu.de\/","name":"kakadoo","description":"","publisher":{"@id":"https:\/\/kakadoo-stu.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kakadoo-stu.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/kakadoo-stu.de\/#organization","name":"kakadoo","url":"https:\/\/kakadoo-stu.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kakadoo-stu.de\/#\/schema\/logo\/image\/","url":"https:\/\/kakadoo-stu.de\/wp-content\/uploads\/2024\/10\/kakadoo-logo.png","contentUrl":"https:\/\/kakadoo-stu.de\/wp-content\/uploads\/2024\/10\/kakadoo-logo.png","width":445,"height":115,"caption":"kakadoo"},"image":{"@id":"https:\/\/kakadoo-stu.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kakadoostudio"]}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/kakadoo-stu.de\/de\/wp-json\/wp\/v2\/pages\/149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kakadoo-stu.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kakadoo-stu.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kakadoo-stu.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kakadoo-stu.de\/de\/wp-json\/wp\/v2\/comments?post=149"}],"version-history":[{"count":3,"href":"https:\/\/kakadoo-stu.de\/de\/wp-json\/wp\/v2\/pages\/149\/revisions"}],"predecessor-version":[{"id":3083,"href":"https:\/\/kakadoo-stu.de\/de\/wp-json\/wp\/v2\/pages\/149\/revisions\/3083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kakadoo-stu.de\/de\/wp-json\/wp\/v2\/media\/215"}],"wp:attachment":[{"href":"https:\/\/kakadoo-stu.de\/de\/wp-json\/wp\/v2\/media?parent=149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}